
{"id":39044,"date":"2024-05-02T08:21:45","date_gmt":"2024-05-02T08:21:45","guid":{"rendered":"https:\/\/voyeglobal.com\/hogar\/"},"modified":"2025-03-19T13:17:13","modified_gmt":"2025-03-19T13:17:13","slug":"hogar","status":"publish","type":"page","link":"https:\/\/esim.lot.com\/es\/","title":{"rendered":"Hogar"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":44,"featured_media":3418,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"views\/tpl-home.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-39044","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voye Global - Servicios eSIM para viajes internacionales<\/title>\n<meta name=\"description\" content=\"Experimente el roaming global sin complicaciones con los innovadores servicios eSIM de Voye. Mant\u00e9ngase conectado sin esfuerzo durante sus viajes con nuestras soluciones personalizadas.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voye Global - Servicios eSIM para viajes internacionales\" \/>\n<meta property=\"og:description\" content=\"Experimente el roaming global sin complicaciones con los innovadores servicios eSIM de Voye. Mant\u00e9ngase conectado sin esfuerzo durante sus viajes con nuestras soluciones personalizadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esim.lot.com\/es\/\" \/>\n<meta property=\"og:site_name\" content=\"Lot\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-19T13:17:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/\",\"url\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/\",\"name\":\"Voye Global - Servicios eSIM para viajes internacionales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esim.lot.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/03\\\/Voye-Logo-OSB.svg\",\"datePublished\":\"2024-05-02T08:21:45+00:00\",\"dateModified\":\"2025-03-19T13:17:13+00:00\",\"description\":\"Experimente el roaming global sin complicaciones con los innovadores servicios eSIM de Voye. Mant\u00e9ngase conectado sin esfuerzo durante sus viajes con nuestras soluciones personalizadas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esim.lot.com\\\/es\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esim.lot.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/03\\\/Voye-Logo-OSB.svg\",\"contentUrl\":\"https:\\\/\\\/esim.lot.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/03\\\/Voye-Logo-OSB.svg\",\"caption\":\"Voye Global\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hogar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/\",\"name\":\"Lot\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esim.lot.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voye Global - Servicios eSIM para viajes internacionales","description":"Experimente el roaming global sin complicaciones con los innovadores servicios eSIM de Voye. Mant\u00e9ngase conectado sin esfuerzo durante sus viajes con nuestras soluciones personalizadas.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Voye Global - Servicios eSIM para viajes internacionales","og_description":"Experimente el roaming global sin complicaciones con los innovadores servicios eSIM de Voye. Mant\u00e9ngase conectado sin esfuerzo durante sus viajes con nuestras soluciones personalizadas.","og_url":"https:\/\/esim.lot.com\/es\/","og_site_name":"Lot","article_modified_time":"2025-03-19T13:17:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/esim.lot.com\/es\/","url":"https:\/\/esim.lot.com\/es\/","name":"Voye Global - Servicios eSIM para viajes internacionales","isPartOf":{"@id":"https:\/\/esim.lot.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esim.lot.com\/es\/#primaryimage"},"image":{"@id":"https:\/\/esim.lot.com\/es\/#primaryimage"},"thumbnailUrl":"https:\/\/esim.lot.com\/wp-content\/uploads\/sites\/7\/2024\/03\/Voye-Logo-OSB.svg","datePublished":"2024-05-02T08:21:45+00:00","dateModified":"2025-03-19T13:17:13+00:00","description":"Experimente el roaming global sin complicaciones con los innovadores servicios eSIM de Voye. Mant\u00e9ngase conectado sin esfuerzo durante sus viajes con nuestras soluciones personalizadas.","breadcrumb":{"@id":"https:\/\/esim.lot.com\/es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esim.lot.com\/es\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esim.lot.com\/es\/#primaryimage","url":"https:\/\/esim.lot.com\/wp-content\/uploads\/sites\/7\/2024\/03\/Voye-Logo-OSB.svg","contentUrl":"https:\/\/esim.lot.com\/wp-content\/uploads\/sites\/7\/2024\/03\/Voye-Logo-OSB.svg","caption":"Voye Global"},{"@type":"BreadcrumbList","@id":"https:\/\/esim.lot.com\/es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/esim.lot.com\/es\/"},{"@type":"ListItem","position":2,"name":"Hogar"}]},{"@type":"WebSite","@id":"https:\/\/esim.lot.com\/es\/#website","url":"https:\/\/esim.lot.com\/es\/","name":"Lot","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esim.lot.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/esim.lot.com\/es\/wp-json\/wp\/v2\/pages\/39044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esim.lot.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/esim.lot.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/esim.lot.com\/es\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/esim.lot.com\/es\/wp-json\/wp\/v2\/comments?post=39044"}],"version-history":[{"count":1,"href":"https:\/\/esim.lot.com\/es\/wp-json\/wp\/v2\/pages\/39044\/revisions"}],"predecessor-version":[{"id":127145,"href":"https:\/\/esim.lot.com\/es\/wp-json\/wp\/v2\/pages\/39044\/revisions\/127145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esim.lot.com\/es\/wp-json\/wp\/v2\/media\/3418"}],"wp:attachment":[{"href":"https:\/\/esim.lot.com\/es\/wp-json\/wp\/v2\/media?parent=39044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}